{"id":6,"count":7,"description":"","link":"https:\/\/www.kehaigascompressor.com\/ar\/%d9%81%d8%a6%d8%a9\/%d9%85%d9%86%d8%aa%d8%ac%d8%a7%d8%aa\/%d8%b6%d8%a7%d8%ba%d8%b7-%d8%a7%d9%84%d9%87%d9%8a%d8%af%d8%b1%d9%88%d8%ac%d9%8a%d9%86\/","name":"\u0636\u0627\u063a\u0637 \u0627\u0644\u0647\u064a\u062f\u0631\u0648\u062c\u064a\u0646","slug":"%d8%b6%d8%a7%d8%ba%d8%b7-%d8%a7%d9%84%d9%87%d9%8a%d8%af%d8%b1%d9%88%d8%ac%d9%8a%d9%86","taxonomy":"category","parent":2,"meta":[],"_links":{"self":[{"href":"https:\/\/www.kehaigascompressor.com\/ar\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kehaigascompressor.com\/ar\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.kehaigascompressor.com\/ar\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.kehaigascompressor.com\/ar\/wp-json\/wp\/v2\/categories\/2"}],"wp:post_type":[{"href":"https:\/\/www.kehaigascompressor.com\/ar\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}